{"id":16899,"date":"2019-12-06T15:00:57","date_gmt":"2019-12-06T14:00:57","guid":{"rendered":"https:\/\/global-exam.com\/blog\/?p=16899"},"modified":"2021-12-21T15:11:38","modified_gmt":"2021-12-21T14:11:38","slug":"cae-speaking-estructura-del-examen-ora","status":"publish","type":"post","link":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/","title":{"rendered":"\u00bfCu\u00e1l es la estructura y las partes del CAE Speaking?"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>El examen de Cambridge que certifica <a href=\"https:\/\/global-exam.com\/blog\/es\/cuales-son-los-niveles-cae\/\">el nivel C1<\/a> es el<strong> llamado CAE<\/strong> y examina a los candidatos en cuatro destrezas: <a href=\"https:\/\/global-exam.com\/blog\/es\/c1-advanced-cae-estructura-de-la-parte-del-reading-y-use-of-english\/\">Reading and Use of English<\/a>, <a href=\"https:\/\/global-exam.com\/blog\/es\/en-que-consiste-la-seccion-de-listening-del-examen-cae\/\">Listening<\/a>, <strong>Speaking y <\/strong><a href=\"https:\/\/global-exam.com\/blog\/es\/cae-writing-cual-es-la-estructura\/\">Writing<\/a>. Es decir, <strong>comprensi\u00f3n escrita <\/strong>y uso de la gram\u00e1tica y del <a href=\"https:\/\/global-exam.com\/blog\/es\/vocabulario-c1-ingles-amplia-tu-vocabulario-para-el-cae\/\">vocabulario en ingl\u00e9s<\/a>, comprensi\u00f3n auditiva, expresi\u00f3n oral y expresi\u00f3n escrita. El objetivo de este examen es <strong>comprobar<\/strong> nuestras <strong>habilidades<\/strong> en <strong>ingl\u00e9s<\/strong> en una <strong>situaci\u00f3n real.<\/strong> La parte del <strong>speaking<\/strong> suele ser la secci\u00f3n que causa m\u00e1s angustia a los candidatos ya que estar\u00e1s frente a un examinador.<\/p>\n<p>En efecto, tendr\u00e1s solamente<strong> 15 minutos<\/strong> para desarrollar tus respuestas, los cuales se dividir\u00e1n entre t\u00fa y otro candidato. Deber\u00e1s entonces utilizar el poco tiempo que tengas para sacar a relucir tu destreza en el idioma, as\u00ed como para hablar lo m\u00e1s que puedas.<\/p>\n<p>Esta parte de la prueba, aunque complicada, no deber\u00eda presentar ning\u00fan problema si tienes la informaci\u00f3n adecuada. Una <strong>buena estructura y preparaci\u00f3n<\/strong> deber\u00edan ser suficientes para que salgas con la cabeza en alto de la sala de examen.<\/p>\n<p>En este art\u00edculo te explicaremos en detalle:<\/p>\n<ul>\n<li>La <strong>estructura<\/strong> del speaking<\/li>\n<li>Los <strong>temas de cada parte<\/strong> del speaking<\/li>\n<li><strong>Tips<\/strong> para esta parte<\/li>\n<li><a href=\"https:\/\/global-exam.com\/es\/exam\/c1-advanced\">Prep\u00e1rate para el CAE<\/a> con GlobalExam<\/li>\n<\/ul>\n<p>\u00bfAre you ready? \u00a1Vamos!<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div style=\"text-align:center;\"><style type=\"text\/css\">.fusion-button.button-1 .fusion-button-text, .fusion-button.button-1 i {color:#ffffff;}.fusion-button.button-1 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-1:hover .fusion-button-text, .fusion-button.button-1:hover i,.fusion-button.button-1:focus .fusion-button-text, .fusion-button.button-1:focus i,.fusion-button.button-1:active .fusion-button-text, .fusion-button.button-1:active{color:#fe6c35;}.fusion-button.button-1:hover .fusion-button-icon-divider, .fusion-button.button-1:hover .fusion-button-icon-divider, .fusion-button.button-1:active .fusion-button-icon-divider{border-color:#fe6c35;}.fusion-button.button-1:hover, .fusion-button.button-1:focus, .fusion-button.button-1:active{border-color:#ffffff;}.fusion-button.button-1 {border-color:#ffffff;border-radius:25px;}.fusion-button.button-1{background: #ff9800;}.fusion-button.button-1:hover,.button-1:focus,.fusion-button.button-1:active{background: #ffaa2b;}<\/style><a class=\"fusion-button button-flat button-large button-custom button-1 fusion-button-span-no fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/auth.global-exam.com\/register\"><span class=\"fusion-button-text\">Practicar gratis al CAE<\/span><\/a><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 30px;margin-bottom : 60px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><h2>\u00bfCu\u00e1l es la estructura del CAE Speaking part?<\/h2>\n<p>Antes de empezar, tienes que saber que el secreto para aprobar un examen es la practica, y esta es la raz\u00f3n por la cu\u00e1l te ponemos a disposici\u00f3n <a href=\"https:\/\/global-exam.com\/blog\/es\/cae-practica-con-una-prueba-online-gratuita-en-globalexam\/\">ex\u00e1menes C1 Cambridge gratis online<\/a> para que puedas entrenarte.<\/p>\n<p>El<strong> speaking part del CAE<\/strong> est\u00e1 compuesta de cuatro secciones, durante las cuales estar\u00e1s acompa\u00f1ado de dos examinadores y de otro candidato. Como en toda conversaci\u00f3n, la primera parte de la prueba consistir\u00e1 en una presentaci\u00f3n, despu\u00e9s de la cual tendr\u00e1s que desarrollar un <strong>mon\u00f3logo<\/strong> sobre una selecci\u00f3n de temas propuestos. En seguida se te pedir\u00e1 <strong>conversar<\/strong> con el <strong>otro<\/strong> <strong>candidato<\/strong> sobre temas de inter\u00e9s <strong>general<\/strong>, para finalmente <strong>desarrollar<\/strong> tus <strong>argumentos<\/strong> sobre alguno de los temas <strong>tratados<\/strong> <strong>previamente<\/strong>.<\/p>\n<p>La parte hablada del <strong>CAE<\/strong> cubre un rango bastante amplio de situaciones y temas, dise\u00f1ados para medir tus capacidades orales en contextos reales. En efecto, pasar\u00e1s de responder preguntas sobre temas cotidianos, a estructurar un argumento, defender tu posici\u00f3n e interactuar con diferentes interlocutores sobre temas cada vez m\u00e1s complejos. Mantenerte atento a las <strong>preguntas<\/strong> y <strong>asumir<\/strong> una <strong>posici\u00f3n<\/strong> activa ser\u00e1n claves para salir airoso de la sala de examen.<\/p>\n\n<table id=\"tablepress-106\" class=\"tablepress tablepress-id-106\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">TAREA<br \/>\n<\/th><th class=\"column-2\">HABILIDADES<\/th><th class=\"column-3\">INTERLOCUTORES<br \/>\n<\/th><th class=\"column-4\">TIEMPO<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">Entrevista<\/td><td class=\"column-2\">Hablar de nosotros mismos<\/td><td class=\"column-3\">Entrevistador y candidato<\/td><td class=\"column-4\">2 minutos<br \/>\n<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">Mon\u00f3logo<br \/>\n<\/td><td class=\"column-2\">Describir, hacer comparaciones, compartir opiniones<\/td><td class=\"column-3\">Candidato 1<br \/>\nCandidato 2<br \/>\nCandidato 2<br \/>\nCandidato 1<\/td><td class=\"column-4\">1,5 minutos cada candidato = 3 minutos<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">Conversaci\u00f3n<br \/>\n<\/td><td class=\"column-2\"><br \/>\nIntercambiar ideas, expresar opiniones, justificarlas y llegar a acuerdos<\/td><td class=\"column-3\">Candidato 1 y candidato 2<\/td><td class=\"column-4\">3 minutos<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">Discusi\u00f3n<\/td><td class=\"column-2\">Expresar opiniones y justificarlas<\/td><td class=\"column-3\">Candidato 1 y candidato 2<\/td><td class=\"column-4\">5 minutos<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<h2>\u00bfCu\u00e1les son los temas de cada parte del CAE Speaking?<\/h2>\n<p><strong>\u00bf<\/strong><a href=\"https:\/\/global-exam.com\/blog\/es\/que-es-el-cambridge-cae-c1-advanced\/\">Qu\u00e9 es el CAE<\/a><strong>? <\/strong>El <strong>examen oral del CAE<\/strong> tiene cuatro partes, en las que habr\u00e1 con nosotros siempre dos examinadores y otro candidato. Uno de los examinadores es el encargado de <strong>administrarnos el examen<\/strong> y el otro es el <strong>corrector<\/strong>, es decir, quien toma notas para <strong>evaluarnos<\/strong> despu\u00e9s.<\/p>\n<p>Como es un <strong>examen<\/strong> para <strong>comprobar<\/strong> nuestra <strong>capacidad de interaccionar<\/strong> y de <strong>expresarnos de manera natural<\/strong>, las tareas est\u00e1n basadas en hablar de nosotros mismos, pero tambi\u00e9n en tener una conversaci\u00f3n con el examinador o con nuestro compa\u00f1ero, por eso tenemos que estar <strong>preparados<\/strong> para cualquier tipo de situaci\u00f3n.<\/p>\n<p><img class=\"aligncenter wp-image-17643 size-medium\" src=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-300x200.jpg\" alt=\"conoce la estructura del CAE speaking \" width=\"300\" height=\"200\" srcset=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-200x134.jpg 200w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-300x200.jpg 300w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-400x267.jpg 400w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-600x401.jpg 600w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-768x513.jpg 768w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1-800x534.jpg 800w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/casual-talking-at-restaurant-table1.jpg 924w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Las partes en las que se divide esta destreza son cuatro y el tiempo m\u00e1ximo de examen ser\u00e1 de <strong>15 minutos<\/strong> para cada dos candidatos. Pero, \u00bfen qu\u00e9 consiste cada una de las tareas?<\/p>\n<h3>Tarea 1 : Entrevista<\/h3>\n<p>En la <a href=\"https:\/\/global-exam.com\/blog\/es\/cambridge-advanced-cae-speaking-part-1-estructura-y-prueba-gratuita\/\">parte 1 del speaking<\/a>\u00a0hablaremos con el <strong>entrevistador<\/strong> y con el otro candidato. El examinador nos har\u00e1 preguntas sobre nuestra vida personal (intereses, gustos, profesi\u00f3n, estudios, etc.) y debemos responder con rapidez y seguridad, ya que esta tarea debe <strong>durar 2 minutos<\/strong>. Lo que <strong>eval\u00faan<\/strong> aqu\u00ed es nuestra <strong>capacidad<\/strong> y habilidad para <strong>dar nuestra opini\u00f3n o hablar<\/strong> sobre nosotros mismos de manera <strong>espont\u00e1nea<\/strong> y <strong>r\u00e1pida<\/strong>.<\/p>\n<h3>Tarea 2 : Mon\u00f3logo<\/h3>\n<p>En la <a href=\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-part-2-conoce-la-estructura-de-esta-parte-de-la-prueba\/\">segunda parte del Speaking<\/a> el examinador nos dar\u00e1 <strong>tres im\u00e1genes<\/strong> con algunas preguntas sobre ellas en la parte superior y tendremos que elegir dos. Despu\u00e9s, tendremos que hablar un <strong>minuto<\/strong> sin parar sobre las <strong>l\u00e1minas<\/strong> que hemos <strong>escogido<\/strong>. Cuando terminemos, el otro candidato har\u00e1 un <strong>resumen<\/strong> y <strong>comentarios<\/strong> de lo que hemos dicho <strong>en 30 segundos<\/strong>. Despu\u00e9s ser\u00e1 el turno del otro candidato, deber\u00e1 hablar tambi\u00e9n un minuto sobre sus <strong>im\u00e1genes<\/strong> (diferentes a las nuestras) y despu\u00e9s nosotros haremos los <strong>comentarios adecuados<\/strong> sobre lo que ha dicho nuestro compa\u00f1ero.<\/p>\n<p>Lo <strong>importante<\/strong> en esta tarea es demostrar que somos <strong>capaces de describir<\/strong>, hacer comparaciones, compartir nuestras opiniones e imaginar lo que puede suceder en las im\u00e1genes. Como tenemos un minuto de tiempo, las preguntas de la parte superior de las l\u00e1minas nos ayudar\u00e1n a <strong>focalizar<\/strong> lo que es necesario apuntar.<\/p>\n<h3>Tarea 3: Conversaci\u00f3n<\/h3>\n<p>La <a href=\"https:\/\/global-exam.com\/blog\/es\/cambridge-advanced-cae-speaking-part-3-estructura-y-prueba-gratuit\/\">tercera parte del speaking<\/a>\u00a0consiste en una <strong>tarea colaborativa<\/strong>, ya que tendremos una <strong>conversaci\u00f3n<\/strong> con el otro candidato. El examinador nos dar\u00e1 algunas <strong>instrucciones<\/strong> sobre el <strong>tema<\/strong> que debemos discutir y nosotros podremos anotar algunas palabras para guiar nuestro discurso. Despu\u00e9s, hablaremos con nuestro compa\u00f1ero dos minutos y el examinador nos pedir\u00e1 que lleguemos a una <strong>conclusi\u00f3n<\/strong> y tomemos una <strong>decisi\u00f3n<\/strong> entre los dos, para lo que discutiremos de nuevo durante un minuto.<\/p>\n<p><img class=\"aligncenter wp-image-17644 size-medium\" src=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-300x200.jpg\" alt=\"conoce los temas de cada parte del CAE speaking \" width=\"300\" height=\"200\" srcset=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-200x133.jpg 200w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-300x200.jpg 300w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-400x267.jpg 400w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-600x400.jpg 600w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-768x512.jpg 768w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor-800x534.jpg 800w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/canada-learning-code-instructor.jpg 925w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>En esta parte del examen, el examinador evaluar\u00e1 nuestra <strong>capacidad para intercambiar ideas<\/strong>, <strong>expresar opiniones<\/strong> y justificarlas mediante sugerencias, propuestas y negociaciones.<\/p>\n<h3>Tarea 4: Discusi\u00f3n<\/h3>\n<p>En la <a href=\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-part-4-en-que-consiste-la-expresion-oral\/\">parte 4 del Speaking<\/a>, que durar\u00e1 <strong>5 minutos<\/strong>, debemos tener una <strong>discusi\u00f3n larga<\/strong> con el otro candidato sobre los temas de la <strong>tarea 3<\/strong>. Nos haran preguntas y justificaremos nuestras opiniones. Tambi\u00e9n, tendremos que debatir con nuestro compa\u00f1ero.<\/p>\n<p>Lo que debemos demostrar aqu\u00ed es nuestra <strong>habilidad<\/strong> para <strong>expresar opiniones y justificarlas<\/strong>.<\/p>\n<p>Si tienes preguntas acerca de la <a href=\"https:\/\/global-exam.com\/blog\/es\/puntuacion-cae-como-funciona-el-puntaje-del-c1-advanced\/\">puntuaci\u00f3n del CAE<\/a>, no dudes en consultar nuestro art\u00edculo sobre el tema.<\/p>\n<h2>Tips para la parte del Speaking CAE<\/h2>\n<ul>\n<li><strong>Escucha<\/strong> <strong>atentamente<\/strong> lo que se te pregunta, pues tu respuesta debe corresponder perfectamente con lo que el examinador espera que respondas. \u00a1No divagues!<\/li>\n<li><strong>Habla<\/strong> hasta m\u00e1s no poder en <strong>ingl\u00e9s<\/strong>. Entrena hablando con amigos, colegas, o incluso compa\u00f1eros de t\u00e1ndem. Intenta emular las condiciones de la prueba, piensa una pregunta y cronometra tu respuesta.<\/li>\n<li><strong>Practica<\/strong> <strong>hablar contigo<\/strong> <strong>mismo<\/strong>. Preg\u00fantate cosas como: \u00bfd\u00f3nde te ves en 5 a\u00f1os?, \u00bfcu\u00e1les son tus hobbies?, \u00bfcu\u00e1les son tus vacaciones so\u00f1adas?. Haz este ejercicio mientras vas en el transporte p\u00fablico, o mientras te duchas, trata que tu respuesta sea en ingl\u00e9s y que sea breve y asertiva.<\/li>\n<li>Haz <strong>tests<\/strong> en <strong>l\u00ednea<\/strong> y <strong>graba<\/strong> <strong>tus respuestas.<\/strong> Escucharte puede serte de gran ayuda para analizar cr\u00edticamente si lo que dices responde a lo que se te pregunta, y para corregir errores de expresi\u00f3n.<\/li>\n<li>En <strong>internet<\/strong> tienes infinidad de <strong>recursos,<\/strong> aprov\u00e9chalos.\u00a0 Escucha <strong>podcasts,<\/strong> mira series, escucha la <strong>radio.<\/strong> Asume una postura activa e interact\u00faa en la discusi\u00f3n, formula ideas, cuestiona. Esto prepara tu cerebro para entablar una conversaci\u00f3n y manejar el tiempo de manera inteligente.<\/li>\n<\/ul>\n<h2>Prep\u00e1rate con GlobalExam<\/h2>\n<p>Con GlobalExam podr\u00e1s<a href=\"https:\/\/global-exam.com\/blog\/es\/cambridge-cae-practice-como-tener-una-preparacion-eficaz\/\"> prepararte al CAE<\/a> a la perfecci\u00f3n para <strong>desarrollar<\/strong> todas las <strong>habilidades<\/strong> en ingl\u00e9s que necesitas para <strong>aprobar<\/strong> este <strong>examen<\/strong>. Nuestra plataforma tiene un \u00e1rea especializada en los ex\u00e1menes de <strong>Cambridge<\/strong> con <a href=\"https:\/\/global-exam.com\/blog\/es\/gramatica-c1-ingles-reglas-y-ejercicios-para-el-cae\/\">reglas de gram\u00e1tica<\/a><strong> y vocabulario<\/strong> con las que estudiar, modelos de ex\u00e1menes para <strong>practicar<\/strong> y un seguimiento para <strong>comprobar tu evoluci\u00f3n<\/strong> y as\u00ed ver en qu\u00e9 punto te encuentras.<\/p>\n<p>Con nuestra versi\u00f3n gratuita podr\u00e1s acceder a 2 ejercicios t\u00edpicos de la prueba C1 Advanced y a 350 hojas de estudios. Sin embargo, si lo que quieres es reforzar tu preparaci\u00f3n al CAE, entonces la versi\u00f3n premium es para t\u00ed. Con esta versi\u00f3n tendr\u00e1s acceso a todas nuestras herramientas que ponemos a tu disposici\u00f3n para que cuando llegue el gr\u00e1n d\u00eda puedas pasarlo sin ning\u00fan problema.<\/p>\n<p>Te presentamos las ciudades donde puedes tomar el <a href=\"https:\/\/global-exam.com\/blog\/es\/cae-espana-cuales-son-los-centros-donde-puedo-pasar-el-c1-advanced\/\">CAE en Espa\u00f1a <\/a>y en <a href=\"https:\/\/global-exam.com\/blog\/es\/cae-mexico-donde-pasar-el-certificado-cambridge-c1-advanced\/\">M\u00e9xico<\/a>.<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-3{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":43463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4258],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CAE Speaking: Estructura del examen oral de ingl\u00e9s del nivel C1<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo es el CAE Speaking part? Conoce la estructura del examen oral de ingl\u00e9s del Cambridge Advanced y sus diferentes partes y temas al detalle. \u00a1Vamos a verlo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAE Speaking: Estructura del examen oral de ingl\u00e9s del nivel C1\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo es el CAE Speaking part? Conoce la estructura del examen oral de ingl\u00e9s del Cambridge Advanced y sus diferentes partes y temas al detalle. \u00a1Vamos a verlo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/\" \/>\n<meta property=\"og:site_name\" content=\"GlobalExam Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Global.Exam\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-06T14:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-21T14:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Global_Exam\" \/>\n<meta name=\"twitter:site\" content=\"@Global_Exam\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/global-exam.com\/blog\/#website\",\"url\":\"https:\/\/global-exam.com\/blog\/\",\"name\":\"GlobalExam Blog\",\"description\":\"Le blog du sp\\u00e9cialiste de la certification linguistique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/global-exam.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg\",\"contentUrl\":\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg\",\"width\":1170,\"height\":541,\"caption\":\"Todo lo que tienes que saber sobre el Speaking CAE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#webpage\",\"url\":\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/\",\"name\":\"CAE Speaking: Estructura del examen oral de ingl\\u00e9s del nivel C1\",\"isPartOf\":{\"@id\":\"https:\/\/global-exam.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#primaryimage\"},\"datePublished\":\"2019-12-06T14:00:57+00:00\",\"dateModified\":\"2021-12-21T14:11:38+00:00\",\"author\":{\"@id\":\"https:\/\/global-exam.com\/blog\/#\/schema\/person\/50fc6f506fe496587b7789d5c174e99d\"},\"description\":\"\\u00bfC\\u00f3mo es el CAE Speaking part? Conoce la estructura del examen oral de ingl\\u00e9s del Cambridge Advanced y sus diferentes partes y temas al detalle. \\u00a1Vamos a verlo!\",\"breadcrumb\":{\"@id\":\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"C1 Advanced\",\"item\":\"https:\/\/global-exam.com\/blog\/es\/examenes\/c1-advanced\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instrucciones - C1 Advanced\",\"item\":\"https:\/\/global-exam.com\/blog\/es\/examenes\/c1-advanced\/categoria-instrucciones-c1-advanced\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\\u00bfCu\\u00e1l es la estructura y las partes del CAE Speaking?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/global-exam.com\/blog\/#\/schema\/person\/50fc6f506fe496587b7789d5c174e99d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/global-exam.com\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8e29f615098aa0e9a914985d7d7d546?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8e29f615098aa0e9a914985d7d7d546?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAE Speaking: Estructura del examen oral de ingl\u00e9s del nivel C1","description":"\u00bfC\u00f3mo es el CAE Speaking part? Conoce la estructura del examen oral de ingl\u00e9s del Cambridge Advanced y sus diferentes partes y temas al detalle. \u00a1Vamos a verlo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/","og_locale":"fr_FR","og_type":"article","og_title":"CAE Speaking: Estructura del examen oral de ingl\u00e9s del nivel C1","og_description":"\u00bfC\u00f3mo es el CAE Speaking part? Conoce la estructura del examen oral de ingl\u00e9s del Cambridge Advanced y sus diferentes partes y temas al detalle. \u00a1Vamos a verlo!","og_url":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/","og_site_name":"GlobalExam Blog","article_publisher":"https:\/\/www.facebook.com\/Global.Exam","article_published_time":"2019-12-06T14:00:57+00:00","article_modified_time":"2021-12-21T14:11:38+00:00","og_image":[{"width":1170,"height":541,"url":"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg","path":"\/home\/forge\/global-exam.com\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg","size":"full","id":43463,"alt":"Todo lo que tienes que saber sobre el Speaking CAE","pixels":632970,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@Global_Exam","twitter_site":"@Global_Exam","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/global-exam.com\/blog\/#website","url":"https:\/\/global-exam.com\/blog\/","name":"GlobalExam Blog","description":"Le blog du sp\u00e9cialiste de la certification linguistique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global-exam.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg","contentUrl":"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2019\/12\/cae-speaking-estructura-e1617699756455.jpeg","width":1170,"height":541,"caption":"Todo lo que tienes que saber sobre el Speaking CAE"},{"@type":"WebPage","@id":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#webpage","url":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/","name":"CAE Speaking: Estructura del examen oral de ingl\u00e9s del nivel C1","isPartOf":{"@id":"https:\/\/global-exam.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#primaryimage"},"datePublished":"2019-12-06T14:00:57+00:00","dateModified":"2021-12-21T14:11:38+00:00","author":{"@id":"https:\/\/global-exam.com\/blog\/#\/schema\/person\/50fc6f506fe496587b7789d5c174e99d"},"description":"\u00bfC\u00f3mo es el CAE Speaking part? Conoce la estructura del examen oral de ingl\u00e9s del Cambridge Advanced y sus diferentes partes y temas al detalle. \u00a1Vamos a verlo!","breadcrumb":{"@id":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/global-exam.com\/blog\/es\/cae-speaking-estructura-del-examen-oral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"C1 Advanced","item":"https:\/\/global-exam.com\/blog\/es\/examenes\/c1-advanced\/"},{"@type":"ListItem","position":2,"name":"Instrucciones - C1 Advanced","item":"https:\/\/global-exam.com\/blog\/es\/examenes\/c1-advanced\/categoria-instrucciones-c1-advanced\/"},{"@type":"ListItem","position":3,"name":"\u00bfCu\u00e1l es la estructura y las partes del CAE Speaking?"}]},{"@type":"Person","@id":"https:\/\/global-exam.com\/blog\/#\/schema\/person\/50fc6f506fe496587b7789d5c174e99d","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/global-exam.com\/blog\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/e8e29f615098aa0e9a914985d7d7d546?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8e29f615098aa0e9a914985d7d7d546?s=96&d=mm&r=g","caption":"admin"}}]}},"lang":"es","translations":{"es":16899},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts\/16899"}],"collection":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/comments?post=16899"}],"version-history":[{"count":35,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts\/16899\/revisions"}],"predecessor-version":[{"id":71227,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts\/16899\/revisions\/71227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/media\/43463"}],"wp:attachment":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/media?parent=16899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/categories?post=16899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/tags?post=16899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}