{"id":74876,"date":"2022-02-02T14:51:29","date_gmt":"2022-02-02T13:51:29","guid":{"rendered":"https:\/\/global-exam.com\/blog\/?p=74876"},"modified":"2022-08-30T11:25:50","modified_gmt":"2022-08-30T09:25:50","slug":"tef-canada-en-quoi-consiste-ce-test%e2%80%89-ou-le-passer-au-maroc%e2%80%89","status":"publish","type":"post","link":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/","title":{"rendered":"TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009?"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>Qu&rsquo;est ce que le TEF ? A quoi sert cet examen et quelles sont les \u00e9preuves ?<\/p>\n<p>D\u00e9couvrez dans cet article\u00a0:<\/p>\n<ul>\n<li>En quoi consiste le TEF Canada<\/li>\n<li>La structure du test TEF Canada<\/li>\n<li>Des exemples d\u2019exercices<\/li>\n<li>Le co\u00fbt du TEF Canada au Maroc<\/li>\n<li>Les sessions pour passer le TEF Canada au Maroc<\/li>\n<li>Les diff\u00e9rences entre le TEF Canada, le TCF et le DELF<\/li>\n<li>Comment s\u2019entra\u00eener au TEF Canada avec GlobalExam<\/li>\n<li>En lisant cet article, vous saurez tout sur le TEF et comment pr\u00e9parer l\u2019\u00e9preuve gr\u00e2ce \u00e0 GlobalExam.<\/li>\n<\/ul>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-center\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-widget-area fusion-widget-area-1 fusion-content-widget-area\"><style type=\"text\/css\">.fusion-widget-area-1 {padding:0px 0px 0px 0px;}.fusion-widget-area-1 .widget h4 {color:#333333;}.fusion-widget-area-1 .widget .heading h4 {color:#333333;}.fusion-widget-area-1 .widget h4 {font-size:18px;}.fusion-widget-area-1 .widget .heading h4 {font-size:18px;}<\/style><div id=\"custom_html-448\" class=\"widget_text widget widget_custom_html\" style=\"border-style: solid;border-color:transparent;border-width:0px;\"><div class=\"textwidget custom-html-widget\"><div class=\"full-widget-flag\"><img class=\"widget-title-icon\" src=\"\/blog\/wp-content\/uploads\/2022\/06\/Trac-34.png\">OFFERT !<\/div>\r\n<div class=\"full-widget-content\">\r\n<h3 class=\"full-widget-title highlight\">\r\n<strong>T\u00e9l\u00e9charger votre guide gratuit<\/strong> de pr\u00e9paration au TCF<\/h3>\r\n\t<div class=\"widget-cta\"><a href=\"\/blog\/fr\/ressources\/ebooks\/ebook-tcf\/\" style=\"color: white !important; text-decoration: none !important;\">J'EN PROFITE !<\/a><\/div><\/div><\/div><\/div><div class=\"fusion-additional-widget-content\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 20px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><h2>Qu\u2019est-ce que le TEF Canada\u2009?<\/h2>\n<p>Le TEF (test d\u2019\u00e9valuation du fran\u00e7ais) est un <strong>examen de langue<\/strong> qui \u00e9value le niveau de <strong>compr\u00e9hension et d\u2019expression du fran\u00e7ais<\/strong> des personnes non francophones. Contrairement au DELF ou au DALF, le TEF est un test progressif multiniveau (du A1 au C2).<\/p>\n<p>Cr\u00e9\u00e9 en 1998 par la CCI d\u2019\u00cele-de-France, le TEF est une r\u00e9f\u00e9rence internationale attestant du niveau de fran\u00e7ais. Le TEF Canada est un test sp\u00e9cifique requis pour toute demande de la citoyennet\u00e9 canadienne et pour certaines demandes de r\u00e9sidence permanente. La validit\u00e9 du TEF est de deux ans.<\/p>\n<h2>Quelles sont les parties du TEF Canada\u2009?<\/h2>\n<p>Le TEF Canada est constitu\u00e9 de 4\u00a0\u00e9preuves\u00a0:<\/p>\n<ul>\n<li><strong>Compr\u00e9hension \u00e9crite<\/strong>\u00a0: 60\u00a0minutes et 50\u00a0questions<\/li>\n<li><strong>Compr\u00e9hension orale<\/strong>\u00a0: 40\u00a0minutes et 60\u00a0questions<\/li>\n<li><strong>Expression \u00e9crite\u00a0<\/strong>: 60\u00a0minutes pour traiter 2\u00a0sujets<\/li>\n<li><strong>Expression orale\u00a0<\/strong>: 15\u00a0minutes pour traiter 2\u00a0sujets<\/li>\n<\/ul>\n<p>Dans le cas d\u2019une immigration au Canada, vous devrez passer les 4\u00a0\u00e9preuves. Pour les personnes qui souhaitent demander la citoyennet\u00e9 canadienne, celles-ci devront passer uniquement les 2\u00a0\u00e9preuves orales\u00a0:<\/p>\n<ul>\n<li>Compr\u00e9hension orale<\/li>\n<li>Expression\u00a0orale<\/li>\n<\/ul>\n<p>A noter que toutes les \u00e9preuves doivent \u00eatre pass\u00e9es le m\u00eame jour afin d\u2019\u00eatre reconnues par les autorit\u00e9s canadiennes.<\/p>\n<h3>L\u2019examen de compr\u00e9hension \u00e9crite<\/h3>\n<ul>\n<li>Objectif\u00a0: \u00e9valuer vos comp\u00e9tences en lecture et compr\u00e9hension d\u2019un document \u00e9crit<\/li>\n<li>Contenu\u00a0: 4 sections avec 50\u00a0questions<\/li>\n<li>Dur\u00e9e\u00a0: 1\u00a0heure<\/li>\n<li>Format\u00a0: questionnaire \u00e0 choix multiples (QCM)<\/li>\n<\/ul>\n<h3>L\u2019examen de compr\u00e9hension orale<\/h3>\n<ul>\n<li>Objectif\u00a0: \u00e9valuer vos comp\u00e9tences en compr\u00e9hension du fran\u00e7ais parl\u00e9 en \u00e9coutant des fichiers sonores<\/li>\n<li>Contenu\u00a0: 4 sections avec 60\u00a0questions<\/li>\n<li>Dur\u00e9e\u00a0: 40\u00a0minutes<\/li>\n<li>Format\u00a0: questionnaire \u00e0 choix multiples (QCM)<\/li>\n<\/ul>\n<h3>L\u2019examen d\u2019expression \u00e9crite<\/h3>\n<ul>\n<li>Objectif : Mesurer votre capacit\u00e9 \u00e0 vous exprimer en fran\u00e7ais \u00e0 l\u2019\u00e9crit.<\/li>\n<li>Contenu : 2 sections<\/li>\n<li>Dur\u00e9e : 1 heure<\/li>\n<li>Format : les sections A et B sont \u00e0 traiter<\/li>\n<\/ul>\n<p>SECTION A \u2013 \u00c9crire la suite d\u2019un article (80 mots minimum)<\/p>\n<p>SECTION B \u2013 Exprimer son point de vue et le justifier (200 mots minimum)<\/p>\n<h3>L\u2019examen d\u2019expression orale<\/h3>\n<ul>\n<li>Objectif\u00a0: \u00e9valuer vos comp\u00e9tences d\u2019expression orale<\/li>\n<li>Contenu\u00a0: 2 sections<\/li>\n<li>Dur\u00e9e\u00a0: 15\u00a0minutes<\/li>\n<li>Le format se pr\u00e9sente sous deux br\u00e8ves entrevues avec un examinateur\u00a0:<\/li>\n<\/ul>\n<p>Section A\u00a0: obtenir des renseignements (5\u00a0minutes)<br \/>\nSection B\u00a0: argumenter pour convaincre (10\u00a0minutes)<\/p>\n<h2>TEF Canada\u00a0: exemples d\u2019exercices<\/h2>\n<p>Vous vous interrogez sur la structure de l\u2019examen\u2009? Voici des exemples d\u2019exercices de compr\u00e9hension orale et \u00e9crite ainsi que d\u2019expression orale et \u00e9crite<\/p>\n<h3>L\u2019\u00e9preuve de compr\u00e9hension \u00e9crite<\/h3>\n<p>Cette partie du test comporte 4 sections pour un total de 50 questions :<\/p>\n<ul>\n<li><strong>Section A\u00a0:<\/strong> 10 questions pour d\u00e9finir la nature, la fonction et les informations principales d&rsquo;un document simple<\/li>\n<li><strong>Section B\u00a0:<\/strong> 25 questions pour comprendre un document dans le d\u00e9tail<\/li>\n<li><strong>Section C\u00a0:<\/strong> 10 questions pour comprendre l\u2019organisation et la logique d\u2019un texte<\/li>\n<li><strong>Section D\u00a0:<\/strong> 5 questions comprendre le sens g\u00e9n\u00e9ral d\u2019une phrase<\/li>\n<\/ul>\n<p>Voici un exemple d\u2019exercice illustrant la section A :<\/p>\n<div id=\"attachment_74884\" style=\"width: 380px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-74884\" class=\"wp-image-74884 size-full\" src=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-ecrite.png\" alt=\"Compr\u00e9hension \u00e9crite du TEF.\" width=\"370\" height=\"512\" srcset=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-ecrite-200x277.png 200w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-ecrite-217x300.png 217w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-ecrite.png 370w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/><p id=\"caption-attachment-74884\" class=\"wp-caption-text\">Source : Le fran\u00e7ais des affaires<\/p><\/div>\n<h3>L\u2019\u00e9preuve de compr\u00e9hension orale<\/h3>\n<p>Ce test se pr\u00e9sente sous la forme d\u2019un QCM avec 60 questions organis\u00e9es en 4 sections\u00a0:<\/p>\n<div id=\"attachment_74886\" style=\"width: 522px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-74886\" class=\"wp-image-74886 size-full\" src=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-orale.png\" alt=\"Cmprehension orale TEF\" width=\"512\" height=\"416\" srcset=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-orale-200x163.png 200w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-orale-300x244.png 300w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-orale-400x325.png 400w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-comprehension-orale.png 512w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><p id=\"caption-attachment-74886\" class=\"wp-caption-text\">Source : Le fran\u00e7ais des affaires<\/p><\/div>\n<h3>L\u2019\u00e9preuve d\u2019expression \u00e9crite<\/h3>\n<p>Cette \u00e9preuve comporte deux sections\u00a0:<\/p>\n<p>A\u00a0: r\u00e9diger la suite d\u2019un article<br \/>\nB\u00a0: exprimer son point de vue et le justifier<br \/>\nVoici un exemple d\u2019exercice illustrant la section B\u00a0:<\/p>\n<div id=\"attachment_74889\" style=\"width: 522px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-74889\" class=\"wp-image-74889 size-full\" src=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite.png\" alt=\"Expression ecrite du tef\" width=\"512\" height=\"511\" srcset=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite-66x66.png 66w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite-150x150.png 150w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite-200x200.png 200w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite-300x300.png 300w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite-400x399.png 400w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-expression-ecrite.png 512w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><p id=\"caption-attachment-74889\" class=\"wp-caption-text\">Source : Le fran\u00e7ais des affaires<\/p><\/div>\n<h3>L\u2019\u00e9preuve d\u2019expression orale<\/h3>\n<p>Cette \u00e9preuve d\u2019une dur\u00e9e de 15 minutes comporte 2 sections\u00a0:<\/p>\n<p>A\u00a0: obtenir des informations au sujet d\u2019un document (5 minutes)<br \/>\nB\u00a0: pr\u00e9senter un document et argumenter (10 minutes)<\/p>\n<p>Voici un exemple d\u2019exercice illustrant la section B\u00a0:<\/p>\n<div id=\"attachment_74891\" style=\"width: 522px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-74891\" class=\"wp-image-74891 size-full\" src=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/expression-orale-tef.png\" alt=\"Expression orale du TEF.\" width=\"512\" height=\"500\" srcset=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/expression-orale-tef-200x195.png 200w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/expression-orale-tef-300x293.png 300w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/expression-orale-tef-400x391.png 400w, https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/expression-orale-tef.png 512w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><p id=\"caption-attachment-74891\" class=\"wp-caption-text\">Source : Le fran\u00e7ais des affaires<\/p><\/div>\n<h2>Le score du TEF<\/h2>\n<p>La notation du TEF est r\u00e9alis\u00e9e sur 699 points. Votre score au TEF permet de d\u00e9terminer votre niveau de ma\u00eetrise de la langue fran\u00e7aise\u00a0selon le cadre europ\u00e9en commun de r\u00e9f\u00e9rence pour les langues (CECRL)\u00a0:<\/p>\n<ul>\n<li>0 \u00e0 99\u00a0: &gt;A1<\/li>\n<li>100 \u00e0 199\u00a0: A1<\/li>\n<li>200 \u00e0 299\u00a0: A2<\/li>\n<li>300 \u00e0 399\u00a0: B1<\/li>\n<li>400 \u00e0 499\u00a0: B2<\/li>\n<li>500 \u00e0 599 : C1<\/li>\n<li>600 \u00e0 699 : C2<\/li>\n<\/ul>\n<p>Depuis le 1er octobre 2019, les autorit\u00e9s canadiennes convertissent le score obtenu au TEF selon le syst\u00e8me de comp\u00e9tences linguistiques canadien (NCLC).<\/p>\n<p>Voici le tableau des correspondances\u00a0:<\/p>\n\n<table id=\"tablepress-3772\" class=\"tablepress tablepress-id-3772\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Score TEF<\/th><th class=\"column-2\">0 \u00e0 99<\/th><th class=\"column-3\">100 \u00e0 199<\/th><th class=\"column-4\">200 \u00e0 299<\/th><th class=\"column-5\">300 \u00e0 399<\/th><th class=\"column-6\">400 \u00e0 499<\/th><th class=\"column-7\">500 \u00e0 599<\/th><th class=\"column-8\">600 \u00e0 699<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">Niveau NCLC<\/td><td class=\"column-2\">0<\/td><td class=\"column-3\">1<\/td><td class=\"column-4\">2-3<\/td><td class=\"column-5\">4-5<\/td><td class=\"column-6\">6-7<\/td><td class=\"column-7\">8-9-10<\/td><td class=\"column-8\">11-12<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<p>Selon votre projet, le niveau \u00e0 atteindre au TEF sera diff\u00e9rent\u00a0:<\/p>\n<ul>\n<li>Score des <strong>travailleurs qualifi\u00e9s<\/strong>\u00a0: au minimum NCLC 7 dans les 4 comp\u00e9tences du test<\/li>\n<li>Score des <strong>m\u00e9tiers sp\u00e9cialis\u00e9s<\/strong>\u00a0: au minimum NCLC 5 dans les \u00e9preuves d\u2019expression et de compr\u00e9hension orale et au minimum NCLC 4 dans les \u00e9preuves d\u2019expression et de compr\u00e9hension \u00e9crites<\/li>\n<li>Score pour les <strong>autres professions<\/strong>\u00a0: selon le classement de la profession figurant dans la Classification Nationale des Professions (CNP) du Canada (NCLC 6 ou 7)<\/li>\n<\/ul>\n<h2>Combien co\u00fbte le TEF au Maroc\u2009?<\/h2>\n<p>Le tarif du TEF Canada au Maroc s\u2019\u00e9l\u00e8ve \u00e0 2 700\u00a0MAD (dirhams).<\/p>\n<h2>Combien de sessions TEF y a-t-il au Maroc\u2009?<\/h2>\n<p>Il existe de tr\u00e8s <strong>nombreux centres d\u2019examen du TEF<\/strong> dans beaucoup de pays. Pour passer le TEF au Maroc, vous devez vous rapprocher de l\u2019Institut Fran\u00e7ais du Maroc. Des centres d\u2019examens sont pr\u00e9sents dans plusieurs villes du pays\u00a0: Agadir, Casablanca, El Jadida, F\u00e8s, Essaouira, K\u00e9nitra, Marrakech, Mekn\u00e8s, Oujda, Rabat, Tanger, T\u00e9touan et Safi.<\/p>\n<p>Il est possible de s\u2019inscrire \u00e0 des sessions d\u2019examen tout au long de l\u2019ann\u00e9e. Les sessions d\u2019examen du TEF Canada sont variables selon les villes. N\u2019h\u00e9sitez pas \u00e0 vous renseigner aupr\u00e8s de l\u2019Institut Fran\u00e7ais du Maroc le plus proche de chez vous\u00a0:<\/p>\n<h2>Les diff\u00e9rences entre TEF Canada, le TCF et le DELF<\/h2>\n<p>Le TEF Canada, TCF et DELF sont trois \u00e9preuves tr\u00e8s similaires qui permettent d\u2019\u00e9valuer votre niveau de fran\u00e7ais\u00a0:<\/p>\n<ul>\n<li><strong>TEF\u00a0: test d\u2019\u00e9valuation du fran\u00e7ais<\/strong><\/li>\n<li><strong>TCF\u00a0: test de connaissance du fran\u00e7ais<\/strong><\/li>\n<li><strong>DELF : dipl\u00f4me d\u2019\u00e9tudes en langue fran\u00e7aise<\/strong><\/li>\n<\/ul>\n<p>Le choix du test d\u00e9pend avant tout de l\u2019objectif que vous recherchez. Voici un comparatif des trois \u00e9preuves de fran\u00e7ais\u00a0:<\/p>\n\n<table id=\"tablepress-3773\" class=\"tablepress tablepress-id-3773\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">&nbsp;<\/th><th class=\"column-2\">TEF Canada<\/th><th class=\"column-3\">TCF<\/th><th class=\"column-4\">DELF<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">Dur\u00e9e de validit\u00e9<\/td><td class=\"column-2\">2\u00a0ans<\/td><td class=\"column-3\">2\u00a0ans<\/td><td class=\"column-4\">\u00c0 vie<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">Objectifs<\/td><td class=\"column-2\">Immigration au Canada ou demande de naturalisation canadienne<\/td><td class=\"column-3\">\u00c9tudes, emploi, immigration en France ou demande de la naturalisation fran\u00e7aise<\/td><td class=\"column-4\">\u00c9tudes, emploi ou immigration dans un pays francophone<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">Organisme<\/td><td class=\"column-2\">Chambre du Commerce et de l\u2019Industrie (CCI) de Paris \u2013 \u00cele-de-France<\/td><td class=\"column-3\">Minist\u00e8re fran\u00e7ais de l\u2019\u00c9ducation nationale<\/td><td class=\"column-4\">Minist\u00e8re fran\u00e7ais de l\u2019\u00c9ducation nationale<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">Niveaux de langue<\/td><td class=\"column-2\">De A1 \u00e0 C2<\/td><td class=\"column-3\">De A1 \u00e0 C2<\/td><td class=\"column-4\">De A1 au C2<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">Format du test<\/td><td class=\"column-2\">Sur ordinateur<\/td><td class=\"column-3\">Sur papier ou sur ordinateur<\/td><td class=\"column-4\">Sur papier ou sur ordinateur<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">Sessions<\/td><td class=\"column-2\">Plusieurs par an<\/td><td class=\"column-3\">Plusieurs par an<\/td><td class=\"column-4\">Plusieurs par an<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">Prix<\/td><td class=\"column-2\">2 700\u00a0dirhams<\/td><td class=\"column-3\">1 700\u00a0dirhams<\/td><td class=\"column-4\">Entre 950 et 1 400 dirhams selon le niveau<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<p>Si vous souhaitez en d\u00e9couvrir plus sur le TCF, voici quelques articles :<\/p>\n<ul>\n<li><a href=\"https:\/\/global-exam.com\/blog\/fr\/presentation-tcf\/\">Pr\u00e9sentation du TCF<\/a><\/li>\n<li><a href=\"https:\/\/global-exam.com\/blog\/fr\/presentation-tcf-tout-public\/\">TCF Tout Public<\/a><\/li>\n<\/ul>\n<h2>Pr\u00e9parez-vous au TEF avec GlobalExam<\/h2>\n<p>Notre plateforme d\u2019auto-apprentissage GlobalExam vous pr\u00e9pare \u00e0 plus de 27 tests de langue certifiants (anglais, fran\u00e7ais, espagnol, allemand et mandarin). Elle est enrichie chaque jour de nouveaux exercices et leurs corrig\u00e9s \u00e9labor\u00e9s par des professionnels des langues.<\/p>\n<p>Nous vous proposons une mine de ressources pour vous entra\u00eener en mode examen afin de vous mettre en situation r\u00e9elle. D\u00e9couvrez nos <strong>fiches de r\u00e9vision pour le vocabulaire et la grammaire<\/strong> afin de consolider vos connaissances. Gr\u00e2ce \u00e0 GlobalExam, vous pouvez suivre votre progression en temps r\u00e9el et rep\u00e9rer les points qui n\u00e9cessitent encore un peu d\u2019entra\u00eenement. Des exercices cibl\u00e9s sont \u00e0 votre disposition pour vous entra\u00eener sur une comp\u00e9tence en particulier.<\/p>\n<p>Avec notre solution en ligne, vous progressez \u00e0 votre <strong>rythme dans la compr\u00e9hension et l\u2019expression \u00e9crites<\/strong> ainsi que dans la compr\u00e9hension et l\u2019expression orales. Notre parcours de r\u00e9vision vous permet de pr\u00e9parer tous les <strong>tests de fran\u00e7ais<\/strong> reconnus \u00e0 l\u2019international\u00a0: <a href=\"https:\/\/global-exam.com\/fr\/exam\/delf\">DELF<\/a>, <a href=\"https:\/\/global-exam.com\/fr\/exam\/dalf\">DALF<\/a>, <a href=\"https:\/\/global-exam.com\/fr\/exam\/tcf\">TCF<\/a> et TEF. Des exercices et examens blancs avec corrig\u00e9s vous aident \u00e0 comprendre votre score dans les d\u00e9tails. N\u2019attendez plus et inscrivez-vous sur GlobalExam pour pr\u00e9parer vos \u00e9preuves de langue et progresser en toute libert\u00e9.<\/p>\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-3{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":24,"featured_media":74905,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2073],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009? - GlobalExam Blog<\/title>\n<meta name=\"description\" content=\"Pr\u00e9parez le TEF Canada et tous vos tests de langue gr\u00e2ce \u00e0 notre plateforme d\u2019auto-apprentissage en ligne GlobalExam. Passer le TEF Canada au Maroc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009? - GlobalExam Blog\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e9parez le TEF Canada et tous vos tests de langue gr\u00e2ce \u00e0 notre plateforme d\u2019auto-apprentissage en ligne GlobalExam. Passer le TEF Canada au Maroc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/\" \/>\n<meta property=\"og:site_name\" content=\"GlobalExam Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Global.Exam\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T13:51:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-30T09:25:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Global_Exam\" \/>\n<meta name=\"twitter:site\" content=\"@Global_Exam\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aude\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/global-exam.com\/blog\/#website\",\"url\":\"https:\/\/global-exam.com\/blog\/\",\"name\":\"GlobalExam Blog\",\"description\":\"Le blog du sp\\u00e9cialiste de la certification linguistique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/global-exam.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg\",\"contentUrl\":\"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg\",\"width\":1170,\"height\":541,\"caption\":\"D\\u00e9couvrez o\\u00f9 passer le TEF Canada au Maroc.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#webpage\",\"url\":\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/\",\"name\":\"TEF Canada : en quoi consiste ce test\\u2009? O\\u00f9 le passer au Maroc\\u2009? - GlobalExam Blog\",\"isPartOf\":{\"@id\":\"https:\/\/global-exam.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#primaryimage\"},\"datePublished\":\"2022-02-02T13:51:29+00:00\",\"dateModified\":\"2022-08-30T09:25:50+00:00\",\"author\":{\"@id\":\"https:\/\/global-exam.com\/blog\/#\/schema\/person\/347ff84774fa929fb1b6f9ec2c9e04cc\"},\"description\":\"Pr\\u00e9parez le TEF Canada et tous vos tests de langue gr\\u00e2ce \\u00e0 notre plateforme d\\u2019auto-apprentissage en ligne GlobalExam. Passer le TEF Canada au Maroc.\",\"breadcrumb\":{\"@id\":\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"TCF\",\"item\":\"https:\/\/global-exam.com\/blog\/fr\/examens\/tcf\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\\u00e9sentation\",\"item\":\"https:\/\/global-exam.com\/blog\/fr\/examens\/tcf\/categorie-presentation-du-test-tcf\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TEF Canada : en quoi consiste ce test\\u2009? O\\u00f9 le passer au Maroc\\u2009?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/global-exam.com\/blog\/#\/schema\/person\/347ff84774fa929fb1b6f9ec2c9e04cc\",\"name\":\"Aude\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/global-exam.com\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9c91b1f887db129f5b6c67b2e774d9f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9c91b1f887db129f5b6c67b2e774d9f4?s=96&d=mm&r=g\",\"caption\":\"Aude\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009? - GlobalExam Blog","description":"Pr\u00e9parez le TEF Canada et tous vos tests de langue gr\u00e2ce \u00e0 notre plateforme d\u2019auto-apprentissage en ligne GlobalExam. Passer le TEF Canada au Maroc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/","og_locale":"fr_FR","og_type":"article","og_title":"TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009? - GlobalExam Blog","og_description":"Pr\u00e9parez le TEF Canada et tous vos tests de langue gr\u00e2ce \u00e0 notre plateforme d\u2019auto-apprentissage en ligne GlobalExam. Passer le TEF Canada au Maroc.","og_url":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/","og_site_name":"GlobalExam Blog","article_publisher":"https:\/\/www.facebook.com\/Global.Exam","article_published_time":"2022-02-02T13:51:29+00:00","article_modified_time":"2022-08-30T09:25:50+00:00","og_image":[{"width":1170,"height":541,"url":"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg","path":"\/home\/forge\/prod-20220704.global-exam.com\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg","size":"full","id":74905,"alt":"D\u00e9couvrez o\u00f9 passer le TEF Canada au Maroc.","pixels":632970,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@Global_Exam","twitter_site":"@Global_Exam","twitter_misc":{"\u00c9crit par":"Aude","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/global-exam.com\/blog\/#website","url":"https:\/\/global-exam.com\/blog\/","name":"GlobalExam Blog","description":"Le blog du sp\u00e9cialiste de la certification linguistique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global-exam.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg","contentUrl":"https:\/\/global-exam.com\/blog\/wp-content\/uploads\/2022\/02\/tef-canada-maroc.jpg","width":1170,"height":541,"caption":"D\u00e9couvrez o\u00f9 passer le TEF Canada au Maroc."},{"@type":"WebPage","@id":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#webpage","url":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/","name":"TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009? - GlobalExam Blog","isPartOf":{"@id":"https:\/\/global-exam.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#primaryimage"},"datePublished":"2022-02-02T13:51:29+00:00","dateModified":"2022-08-30T09:25:50+00:00","author":{"@id":"https:\/\/global-exam.com\/blog\/#\/schema\/person\/347ff84774fa929fb1b6f9ec2c9e04cc"},"description":"Pr\u00e9parez le TEF Canada et tous vos tests de langue gr\u00e2ce \u00e0 notre plateforme d\u2019auto-apprentissage en ligne GlobalExam. Passer le TEF Canada au Maroc.","breadcrumb":{"@id":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/global-exam.com\/blog\/fr\/tef-canada-en-quoi-consiste-ce-test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"TCF","item":"https:\/\/global-exam.com\/blog\/fr\/examens\/tcf\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9sentation","item":"https:\/\/global-exam.com\/blog\/fr\/examens\/tcf\/categorie-presentation-du-test-tcf\/"},{"@type":"ListItem","position":3,"name":"TEF Canada : en quoi consiste ce test\u2009? O\u00f9 le passer au Maroc\u2009?"}]},{"@type":"Person","@id":"https:\/\/global-exam.com\/blog\/#\/schema\/person\/347ff84774fa929fb1b6f9ec2c9e04cc","name":"Aude","image":{"@type":"ImageObject","@id":"https:\/\/global-exam.com\/blog\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/9c91b1f887db129f5b6c67b2e774d9f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c91b1f887db129f5b6c67b2e774d9f4?s=96&d=mm&r=g","caption":"Aude"}}]}},"lang":"fr","translations":{"fr":74876},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts\/74876"}],"collection":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/comments?post=74876"}],"version-history":[{"count":6,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts\/74876\/revisions"}],"predecessor-version":[{"id":79047,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/posts\/74876\/revisions\/79047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/media\/74905"}],"wp:attachment":[{"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/media?parent=74876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/categories?post=74876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global-exam.com\/blog\/wp-json\/wp\/v2\/tags?post=74876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}